{"id":9101,"date":"2025-11-20T16:01:56","date_gmt":"2025-11-20T08:01:56","guid":{"rendered":"https:\/\/www.vingloop.com\/?post_type=portfolio&#038;p=9101"},"modified":"2025-12-09T19:03:52","modified_gmt":"2025-12-09T11:03:52","slug":"lumens","status":"publish","type":"portfolio","link":"https:\/\/www.vingloop.com\/es\/portfolio\/lumens\/","title":{"rendered":"L\u00famenes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"9101\" class=\"elementor elementor-9101\">\n\t\t\t\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-1caca14 elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"1caca14\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-365bede\" data-id=\"365bede\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-689c6f0 elementor-widget elementor-widget-image\" data-id=\"689c6f0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.7 - 20-09-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1040\" height=\"1040\" src=\"https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN.png 1040w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-300x300.png 300w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-800x800.png 800w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-150x150.png 150w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-768x768.png 768w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-12x12.png 12w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-860x860.png 860w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-430x430.png 430w, https:\/\/www.vingloop.com\/wp-content\/uploads\/2025\/11\/Lumens_Vingloop_Partnership_EN-700x700.png 700w\" sizes=\"auto, (max-width: 1040px) 100vw, 1040px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f6c251\" data-id=\"9f6c251\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0aae244 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"0aae244\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.7 - 20-09-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><span dir=\"LTR\">Lumens\u00ae Digital Optics Inc, una empresa del Grupo Pegatron, es l\u00edder en productos \u00f3pticos. La oferta de productos de Lumens incluye CamConnect Pro, c\u00e1maras PTZ HD y 4K, c\u00e1maras de seguimiento y encuadre autom\u00e1tico, procesadores multimedia, transmisores y descodificadores IP y c\u00e1maras de documentos. Fundada en 1998, la empresa fue creada por un equipo con un profundo patrimonio tecnol\u00f3gico en procesamiento de im\u00e1genes, electr\u00f3nica de v\u00eddeo y tecnolog\u00eda \u00f3ptica. Con el apoyo del Grupo Pegatron, Lumens mejora continuamente los dise\u00f1os de sus productos para utilizarlos en estudios de v\u00eddeo, eventos en directo, aulas, salas de conferencias y para la ense\u00f1anza a distancia.<\/span><span dir=\"LTR\"><br \/><\/span><span dir=\"LTR\"><br \/><\/span><span dir=\"LTR\">La integraci\u00f3n de los conmutadores IP mejorados con IA de Vingloop con la tecnolog\u00eda IP, NDI y Dante de Lumens ofrecer\u00e1 verdaderas capacidades plug-and-play y una implementaci\u00f3n m\u00e1s sencilla de AV a trav\u00e9s de redes Ethernet.<\/span><\/p><p><span dir=\"LTR\"><br \/><\/span><span dir=\"LTR\">Lumens ha certificado los conmutadores AIG-8G2GF-PoE, AIM-24MG6XF-UPoE y AIX-24XF4CF de Vingloop como totalmente interoperables con sus c\u00e1maras IP, procesadores multimedia y productos AV-over-IP. Estos conmutadores est\u00e1n preconfigurados para admitir formatos de transmisi\u00f3n ampliamente adoptados, lo que proporciona una base estable y escalable para los flujos de trabajo multimedia modernos.<\/span><\/p><p><span dir=\"LTR\"><br \/><\/span><span dir=\"LTR\">Para m\u00e1s informaci\u00f3n sobre Lumens y la soluci\u00f3n de integraci\u00f3n Vingloop, visite:<\/span><\/p><p><a href=\"https:\/\/www.mylumens.com\/en\/Page\/164\/lumens-partner-vingloop-professional-av-networking-solution\"><u><span dir=\"LTR\">https:\/\/www.mylumens.com\/en\/Page\/164\/lumens-partner-vingloop-professional-av-networking-solution<\/span><\/u><\/a><\/p><p style=\"margin: 0pt 0pt 0.0001pt; line-height: 16.72px; font-family: Arial; font-size: 11pt; color: #000000; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400;\">\u00a0<\/p><p style=\"margin: 0pt 0pt 0.0001pt; line-height: 16.72px; font-family: Arial; font-size: 11pt; color: #000000; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400;\">\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Lumens\u00ae Digital Optics Inc., a Pegatron Group company, is a leader in optical products. Lumens\u2019 product offerings include CamConnect Pro,<\/p>","protected":false},"featured_media":9088,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[],"class_list":["post-9101","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/portfolio\/9101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/comments?post=9101"}],"version-history":[{"count":13,"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/portfolio\/9101\/revisions"}],"predecessor-version":[{"id":9194,"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/portfolio\/9101\/revisions\/9194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/media\/9088"}],"wp:attachment":[{"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/media?parent=9101"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/www.vingloop.com\/es\/wp-json\/wp\/v2\/project-cat?post=9101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}